{"id":188,"date":"2016-11-09T12:33:38","date_gmt":"2016-11-09T12:33:38","guid":{"rendered":"http:\/\/quanticalabs.com\/wp_themes2\/portada\/?page_id=188"},"modified":"2016-11-09T12:33:38","modified_gmt":"2016-11-09T12:33:38","slug":"iframe","status":"publish","type":"page","link":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/shortcode\/iframe\/","title":{"rendered":"Iframe"},"content":{"rendered":"<p><h3 class=\"pb-header\"><span class=\"pb-header-content\">Sample I<\/span><\/h3><br \/>\n<div class=\"pb-iframe\"><div class=\"pb-iframe-content\" style=\"height:500px;padding-bottom:0px;\"><iframe src=\"http:\/\/quanticalabs.com\/NostalgiaLanding\/Template\/\"><\/iframe><\/div><\/div><br \/>\n<div id=\"pb_preformatted_text_E337D6FB51032E3B94C2360E22D2DCD8\" class=\"pb-preformatted-text pb-bottom-0\"><div><a href=\"#\"><span class=\"pb-preformatted-text-label-open\">- Hide code<\/span><span class=\"pb-preformatted-text-label-close\">+ Show code<\/span><\/a><\/div><pre>&lt;br \/&gt;<br \/>&#091;pb_iframe src=&quot;http:\/\/quanticalabs.com\/NostalgiaLanding\/Template\/&quot; height=&quot;500&quot;&#093;&#091;\/pb_iframe&#093;&lt;br \/&gt;<\/pre><\/div><div class=\"pb-script-tag\"><script type=\"text\/javascript\">jQuery(document).ready(function($) {$(\"#pb_preformatted_text_E337D6FB51032E3B94C2360E22D2DCD8\").PBPreformattedText();});<\/script><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":172,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":[],"_links":{"self":[{"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/pages\/188"}],"collection":[{"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":0,"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/pages\/188\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/pages\/172"}],"wp:attachment":[{"href":"https:\/\/quanticalabs.com\/wp_themes3\/portada2\/wp-json\/wp\/v2\/media?parent=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}